{"id":573,"date":"2024-07-23T11:55:48","date_gmt":"2024-07-23T09:55:48","guid":{"rendered":"https:\/\/fischer-weine.dev7\/cms\/?page_id=573"},"modified":"2024-10-14T11:49:08","modified_gmt":"2024-10-14T09:49:08","slug":"weinwissen","status":"publish","type":"page","link":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/","title":{"rendered":"Weinwissen"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1568,"parent":532,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-573","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weinwissen - Fischer Weine<\/title>\n<meta name=\"description\" content=\"Weinwissen - Erlesenes, internationales Wein-&amp; Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weinwissen - Fischer Weine\" \/>\n<meta property=\"og:description\" content=\"Weinwissen - Erlesenes, internationales Wein-&amp; Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/\" \/>\n<meta property=\"og:site_name\" content=\"Fischer Weine\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T09:49:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fischer-weine.ch\/cms\/wp-content\/uploads\/2024\/09\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/\",\"url\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/\",\"name\":\"Weinwissen - Fischer Weine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg\",\"datePublished\":\"2024-07-23T09:55:48+00:00\",\"dateModified\":\"2024-10-14T09:49:08+00:00\",\"description\":\"Weinwissen - Erlesenes, internationales Wein-& Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg\",\"width\":2000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/weinwissen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Weinwelt\",\"item\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/weinwelt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weinwissen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/#website\",\"url\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/\",\"name\":\"Fischer Weine\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fischer-weine.ch\\\/cms\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weinwissen - Fischer Weine","description":"Weinwissen - Erlesenes, internationales Wein-& Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/","og_locale":"de_DE","og_type":"article","og_title":"Weinwissen - Fischer Weine","og_description":"Weinwissen - Erlesenes, internationales Wein-& Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen","og_url":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/","og_site_name":"Fischer Weine","article_modified_time":"2024-10-14T09:49:08+00:00","og_image":[{"width":2000,"height":1500,"url":"https:\/\/www.fischer-weine.ch\/cms\/wp-content\/uploads\/2024\/09\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/","url":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/","name":"Weinwissen - Fischer Weine","isPartOf":{"@id":"https:\/\/www.fischer-weine.ch\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/#primaryimage"},"image":{"@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fischer-weine.ch\/cms\/wp-content\/uploads\/2024\/09\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg","datePublished":"2024-07-23T09:55:48+00:00","dateModified":"2024-10-14T09:49:08+00:00","description":"Weinwissen - Erlesenes, internationales Wein-& Spirituosen-Sortiment. Im Weinhandel Fischer Weine Sursee kaufen \u2713oder bequem von Zuhause \u00fcber den Weinversand bestellen","breadcrumb":{"@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/#primaryimage","url":"https:\/\/www.fischer-weine.ch\/cms\/wp-content\/uploads\/2024\/09\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg","contentUrl":"https:\/\/www.fischer-weine.ch\/cms\/wp-content\/uploads\/2024\/09\/anna-fischer-und-ihr-rosa-sprudel-mobile.jpg","width":2000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/weinwissen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fischer-weine.ch\/cms\/"},{"@type":"ListItem","position":2,"name":"Weinwelt","item":"https:\/\/www.fischer-weine.ch\/cms\/weinwelt\/"},{"@type":"ListItem","position":3,"name":"Weinwissen"}]},{"@type":"WebSite","@id":"https:\/\/www.fischer-weine.ch\/cms\/#website","url":"https:\/\/www.fischer-weine.ch\/cms\/","name":"Fischer Weine","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fischer-weine.ch\/cms\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/pages\/573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/comments?post=573"}],"version-history":[{"count":23,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/pages\/573\/revisions"}],"predecessor-version":[{"id":2182,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/pages\/573\/revisions\/2182"}],"up":[{"embeddable":true,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/pages\/532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/media\/1568"}],"wp:attachment":[{"href":"https:\/\/www.fischer-weine.ch\/cms\/wp-json\/wp\/v2\/media?parent=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}